{"id":39,"date":"2016-07-05T14:49:02","date_gmt":"2016-07-05T14:49:02","guid":{"rendered":"http:\/\/flatsome.dev\/?page_id=8220"},"modified":"2025-02-09T10:40:07","modified_gmt":"2025-02-09T10:40:07","slug":"grid-style-3","status":"publish","type":"page","link":"https:\/\/keepinltd.com\/en\/demos\/shop-demos\/grid-style-3\/","title":{"rendered":"Grid Style 3"},"content":{"rendered":"\n\t<section class=\"section has-parallax\" id=\"section_1324179177\">\n\t\t<div class=\"section-bg fill\" data-parallax-container=\".section\" data-parallax-background data-parallax=\"-3\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"650\" src=\"https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-2.jpg\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:1px 0px 1px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n  <div class=\"banner-grid-wrapper\">\n  <div id=\"banner-grid-580075835\" class=\"banner-grid row row-grid row-small\" data-packery-options=\"\">\n                      \n<div class=\"col grid-col small-12 large-6 grid-col-1\" ><div class=\"col-inner box-shadow-1\">\n\n  <div class=\"banner has-hover bg-zoom-fade\" id=\"banner-832263209\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"650\" src=\"https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-2.jpg\" class=\"bg attachment-large size-large\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-531651368\" class=\"text-box banner-layer x10 md-x10 lg-x10 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text \">\n              \n              <div class=\"text-inner text-left\">\n                  \n<p class=\"lead alt-font\"><span style=\"font-size: 190%;\">Add any text here&#8230;<\/span><\/p>\n<h2 class=\"uppercase\"><span style=\"font-size: 130%;\"><strong>New arrivals on the shop<\/strong><\/span><\/h2>\n<div class=\"is-divider divider clearfix\" ><\/div>\n<a class=\"button primary is-outline is-larger\"  >\n\t\t<span>Browse<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-531651368 {\n  width: 50%;\n}\n#text-box-531651368 .text-box-content {\n  font-size: 99%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-832263209 {\n  padding-top: 500px;\n  background-color: rgb(255, 255, 255);\n}\n#banner-832263209 .banner-bg img {\n  object-position: 65% 16%;\n}\n<\/style>\n  <\/div>\n\n\n<\/div><\/div>\n<div class=\"col grid-col small-7 large-3 grid-col-1\" ><div class=\"col-inner box-shadow-1\">\n\n  <div class=\"banner has-hover bg-zoom-fade\" id=\"banner-1573351647\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-2-300x195.jpg\" class=\"bg attachment-medium size-medium\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-294411757\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h2 class=\"uppercase\"><strong>Add Any Headline here<\/strong><\/h2>\n<div class=\"is-divider divider clearfix\" ><\/div>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-294411757 {\n  width: 60%;\n}\n#text-box-294411757 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-294411757 {\n    width: 76%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1573351647 {\n  padding-top: 500px;\n}\n#banner-1573351647 .banner-bg img {\n  object-position: 58% 24%;\n}\n<\/style>\n  <\/div>\n\n\n<\/div><\/div>\n<div class=\"col grid-col small-5 large-3 grid-col-1-2\" ><div class=\"col-inner box-shadow-1\">\n\n  <div class=\"banner has-hover bg-zoom-fade\" id=\"banner-49385053\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-2-300x195.jpg\" class=\"bg attachment-medium size-medium\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-640274886\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h2 class=\"uppercase\"><strong>Add Any Headline here<\/strong><\/h2>\n<div class=\"is-divider divider clearfix\" ><\/div>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-640274886 {\n  width: 60%;\n}\n#text-box-640274886 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-640274886 {\n    width: 67%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-49385053 {\n  padding-top: 500px;\n}\n<\/style>\n  <\/div>\n\n\n<\/div><\/div>\n<div class=\"col grid-col small-5 large-3 grid-col-1-2\" ><div class=\"col-inner box-shadow-1\">\n\n  <div class=\"banner has-hover bg-zoom-fade\" id=\"banner-632665214\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-2-300x195.jpg\" class=\"bg attachment-medium size-medium\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1720781922\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h2 class=\"uppercase\"><strong>Add Any Headline here<\/strong><\/h2>\n<div class=\"is-divider divider clearfix\" ><\/div>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1720781922 {\n  width: 60%;\n}\n#text-box-1720781922 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1720781922 {\n    width: 68%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-632665214 {\n  padding-top: 500px;\n}\n<\/style>\n  <\/div>\n\n\n<\/div><\/div>\n            <\/div>\n    <style>\n    #banner-grid-580075835 .grid-col-1{height: 600px}\n    #banner-grid-580075835 .grid-col-1-2{height: 300px}\n    #banner-grid-580075835 .grid-col-1-3{height:200px}\n    #banner-grid-580075835 .grid-col-2-3{height: 400px}\n    #banner-grid-580075835 .grid-col-1-4{height: 150px}\n    #banner-grid-580075835 .grid-col-3-4{height: 450px}\n\n\n    \n    \n\n  <\/style>\n    <\/div>\n  \n\t\t<\/div>\n\n\t\t\n<style>\n#section_1324179177 {\n  padding-top: 19px;\n  padding-bottom: 19px;\n  background-color: rgb(246, 246, 246);\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"container section-title-container\" style=\"margin-top:22px;\"><h3 class=\"section-title section-title-bold-center\"><b><\/b><span class=\"section-title-main\" style=\"font-size:undefined%;\">Featured Products<\/span><b><\/b><\/h3><\/div>\n\t\n  \n    <div class=\"row large-columns-4 medium-columns-3 small-columns-2 row-small slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <\/div>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-bold-center\"><b><\/b><span class=\"section-title-main\" style=\"font-size:undefined%;\">Featured Categories<\/span><b><\/b><\/h3><\/div>\n\n  \n    <div class=\"row large-columns-4 medium-columns-3 small-columns-2 row-small slider row-slider slider-nav-reveal\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <div class=\"product-category col\" >\n            <div class=\"col-inner\">\n              <a aria-label=\"Visit product category Bags\" href=\"https:\/\/keepinltd.com\/en\/product-category\/bags\/\">                <div class=\"box box-category has-hover box-badge hover-dark \">\n                <div class=\"box-image\" >\n                  <div class=\"\" >\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/keepinltd.com\/wp-content\/uploads\/woocommerce-placeholder-300x300.png\" alt=\"Bags\" width=\"300\" height=\"300\" \/>                                                      <\/div>\n                <\/div>\n                <div class=\"box-text text-center\" >\n                  <div class=\"box-text-inner\">\n                      <h5 class=\"uppercase header-title\">\n                              Bags                      <\/h5>\n                                            <p class=\"is-xsmall uppercase count \">\n\t                      6 Products                      <\/p>\n                                            \n                  <\/div>\n                <\/div>\n                <\/div>\n            <\/a>            <\/div>\n            <\/div><div class=\"product-category col\" >\n            <div class=\"col-inner\">\n              <a aria-label=\"Visit product category Booking\" href=\"https:\/\/keepinltd.com\/en\/product-category\/booking\/\">                <div class=\"box box-category has-hover box-badge hover-dark \">\n                <div class=\"box-image\" >\n                  <div class=\"\" >\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/keepinltd.com\/wp-content\/uploads\/woocommerce-placeholder-300x300.png\" alt=\"Booking\" width=\"300\" height=\"300\" \/>                                                      <\/div>\n                <\/div>\n                <div class=\"box-text text-center\" >\n                  <div class=\"box-text-inner\">\n                      <h5 class=\"uppercase header-title\">\n                              Booking                      <\/h5>\n                                            <p class=\"is-xsmall uppercase count \">\n\t                      6 Products                      <\/p>\n                                            \n                  <\/div>\n                <\/div>\n                <\/div>\n            <\/a>            <\/div>\n            <\/div><div class=\"product-category col\" >\n            <div class=\"col-inner\">\n              <a aria-label=\"Visit product category Clothing\" href=\"https:\/\/keepinltd.com\/en\/product-category\/clothing\/\">                <div class=\"box box-category has-hover box-badge hover-dark \">\n                <div class=\"box-image\" >\n                  <div class=\"\" >\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/keepinltd.com\/wp-content\/uploads\/woocommerce-placeholder-300x300.png\" alt=\"Clothing\" width=\"300\" height=\"300\" \/>                                                      <\/div>\n                <\/div>\n                <div class=\"box-text text-center\" >\n                  <div class=\"box-text-inner\">\n                      <h5 class=\"uppercase header-title\">\n                              Clothing                      <\/h5>\n                                            <p class=\"is-xsmall uppercase count \">\n\t                      3 Products                      <\/p>\n                                            \n                  <\/div>\n                <\/div>\n                <\/div>\n            <\/a>            <\/div>\n            <\/div><div class=\"product-category col\" >\n            <div class=\"col-inner\">\n              <a aria-label=\"Visit product category Men\" href=\"https:\/\/keepinltd.com\/en\/product-category\/men\/\">                <div class=\"box box-category has-hover box-badge hover-dark \">\n                <div class=\"box-image\" >\n                  <div class=\"\" >\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/keepinltd.com\/wp-content\/uploads\/woocommerce-placeholder-300x300.png\" alt=\"Men\" width=\"300\" height=\"300\" \/>                                                      <\/div>\n                <\/div>\n                <div class=\"box-text text-center\" >\n                  <div class=\"box-text-inner\">\n                      <h5 class=\"uppercase header-title\">\n                              Men                      <\/h5>\n                                            <p class=\"is-xsmall uppercase count \">\n\t                      9 Products                      <\/p>\n                                            \n                  <\/div>\n                <\/div>\n                <\/div>\n            <\/a>            <\/div>\n            <\/div><div class=\"product-category col\" >\n            <div class=\"col-inner\">\n              <a aria-label=\"Visit product category Music\" href=\"https:\/\/keepinltd.com\/en\/product-category\/music\/\">                <div class=\"box box-category has-hover box-badge hover-dark \">\n                <div class=\"box-image\" >\n                  <div class=\"\" >\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/keepinltd.com\/wp-content\/uploads\/woocommerce-placeholder-300x300.png\" alt=\"Music\" width=\"300\" height=\"300\" \/>                                                      <\/div>\n                <\/div>\n                <div class=\"box-text text-center\" >\n                  <div class=\"box-text-inner\">\n                      <h5 class=\"uppercase header-title\">\n                              Music                      <\/h5>\n                                            <p class=\"is-xsmall uppercase count \">\n\t                      6 Products                      <\/p>\n                                            \n                  <\/div>\n                <\/div>\n                <\/div>\n            <\/a>            <\/div>\n            <\/div><div class=\"product-category col\" >\n            <div class=\"col-inner\">\n              <a aria-label=\"Visit product category Posters\" href=\"https:\/\/keepinltd.com\/en\/product-category\/posters\/\">                <div class=\"box box-category has-hover box-badge hover-dark \">\n                <div class=\"box-image\" >\n                  <div class=\"\" >\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/keepinltd.com\/wp-content\/uploads\/woocommerce-placeholder-300x300.png\" alt=\"Posters\" width=\"300\" height=\"300\" \/>                                                      <\/div>\n                <\/div>\n                <div class=\"box-text text-center\" >\n                  <div class=\"box-text-inner\">\n                      <h5 class=\"uppercase header-title\">\n                              Posters                      <\/h5>\n                                            <p class=\"is-xsmall uppercase count \">\n\t                      5 Products                      <\/p>\n                                            \n                  <\/div>\n                <\/div>\n                <\/div>\n            <\/a>            <\/div>\n            <\/div><div class=\"product-category col\" >\n            <div class=\"col-inner\">\n              <a aria-label=\"Visit product category Shoes\" href=\"https:\/\/keepinltd.com\/en\/product-category\/shoes\/\">                <div class=\"box box-category has-hover box-badge hover-dark \">\n                <div class=\"box-image\" >\n                  <div class=\"\" >\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/keepinltd.com\/wp-content\/uploads\/woocommerce-placeholder-300x300.png\" alt=\"Shoes\" width=\"300\" height=\"300\" \/>                                                      <\/div>\n                <\/div>\n                <div class=\"box-text text-center\" >\n                  <div class=\"box-text-inner\">\n                      <h5 class=\"uppercase header-title\">\n                              Shoes                      <\/h5>\n                                            <p class=\"is-xsmall uppercase count \">\n\t                      7 Products                      <\/p>\n                                            \n                  <\/div>\n                <\/div>\n                <\/div>\n            <\/a>            <\/div>\n            <\/div><div class=\"product-category col\" >\n            <div class=\"col-inner\">\n              <a aria-label=\"Visit product category Sweaters\" href=\"https:\/\/keepinltd.com\/en\/product-category\/sweaters\/\">                <div class=\"box box-category has-hover box-badge hover-dark \">\n                <div class=\"box-image\" >\n                  <div class=\"\" >\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/keepinltd.com\/wp-content\/uploads\/woocommerce-placeholder-300x300.png\" alt=\"Sweaters\" width=\"300\" height=\"300\" \/>                                                      <\/div>\n                <\/div>\n                <div class=\"box-text text-center\" >\n                  <div class=\"box-text-inner\">\n                      <h5 class=\"uppercase header-title\">\n                              Sweaters                      <\/h5>\n                                            <p class=\"is-xsmall uppercase count \">\n\t                      7 Products                      <\/p>\n                                            \n                  <\/div>\n                <\/div>\n                <\/div>\n            <\/a>            <\/div>\n            <\/div><div class=\"product-category col\" >\n            <div class=\"col-inner\">\n              <a aria-label=\"Visit product category Women\" href=\"https:\/\/keepinltd.com\/en\/product-category\/women\/\">                <div class=\"box box-category has-hover box-badge hover-dark \">\n                <div class=\"box-image\" >\n                  <div class=\"\" >\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/keepinltd.com\/wp-content\/uploads\/woocommerce-placeholder-300x300.png\" alt=\"Women\" width=\"300\" height=\"300\" \/>                                                      <\/div>\n                <\/div>\n                <div class=\"box-text text-center\" >\n                  <div class=\"box-text-inner\">\n                      <h5 class=\"uppercase header-title\">\n                              Women                      <\/h5>\n                                            <p class=\"is-xsmall uppercase count \">\n\t                      15 Products                      <\/p>\n                                            \n                  <\/div>\n                <\/div>\n                <\/div>\n            <\/a>            <\/div>\n            <\/div><\/div>\n\t<div id=\"gap-505051042\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-505051042 {\n  padding-top: 36px;\n}\n<\/style>\n\t<\/div>\n\t\n\n  <div class=\"banner has-hover has-parallax\" id=\"banner-2021853425\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" data-parallax=\"-1\" data-parallax-container=\".banner\" data-parallax-background>\n            <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"650\" src=\"https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-2.jpg\" class=\"bg attachment-large size-large\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-223982746\" class=\"text-box banner-layer x10 md-x10 lg-x10 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"uppercase\"><strong>Signup for Newsletter<\/strong><\/h3>\n<p class=\"lead\">Lorem ipsum dolor sit amet, consectetuer adipiscing elit, sed diam nonumm.<\/p>\n\t<div id=\"gap-1712579972\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1712579972 {\n  padding-top: 18px;\n}\n<\/style>\n\t<\/div>\n\t\n<p>(insert contact form here)<\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-223982746 {\n  width: 78%;\n}\n#text-box-223982746 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-223982746 {\n    width: 37%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-2021853425 {\n  padding-top: 366px;\n}\n#banner-2021853425 .overlay {\n  background-color: rgba(0, 0, 0, 0.26);\n}\n#banner-2021853425 .banner-bg img {\n  object-position: 60% 0%;\n}\n<\/style>\n  <\/div>\n\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-bold-center\"><b><\/b><span class=\"section-title-main\" style=\"font-size:undefined%;\">Latest news<\/span><b><\/b><\/h3><\/div>\n\n  \n    <div class=\"row large-columns-3 medium-columns- small-columns-1 slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-text-bottom box-blog-post has-hover\">\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/keepinltd.com\/en\/2025\/02\/09\/blog-post-title\/\" class=\"plain\">\u90e8\u843d\u683c\u8cbc\u6587\u6a19\u984c<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t<div class=\"post-meta is-small op-8\">February 9, 2025<\/div>\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\t\u90e8\u843d\u683c\u8cbc\u6587\u61c9\u8a72\u6ce8\u610f\u54ea\u4e9b\u4e8b\u9805\uff1f\u63d0 [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-text-bottom box-blog-post has-hover\">\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/keepinltd.com\/en\/2025\/02\/09\/hello-world\/\" class=\"plain\">Hello world!<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t<div class=\"post-meta is-small op-8\">February 9, 2025<\/div>\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tWelcome to Word [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:200px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/keepinltd.com\/en\/2015\/11\/19\/welcome-to-flatsome\/\" class=\"plain\" aria-label=\"Welcome to Flatsome\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/keepinltd.com\/en\/2015\/11\/19\/welcome-to-flatsome\/\" class=\"plain\">Welcome to Flatsome<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tWelcome to Word [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">19<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Nov<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:200px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/keepinltd.com\/en\/2015\/10\/13\/velkommen-til-bloggen-min\/\" class=\"plain\" aria-label=\"Just another post with A Gallery\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/keepinltd.com\/en\/2015\/10\/13\/velkommen-til-bloggen-min\/\" class=\"plain\">Just another post with A Gallery<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tLorem ipsum dol [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">13<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Oct<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:200px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/keepinltd.com\/en\/2015\/10\/13\/a-simple-blog-post\/\" class=\"plain\" aria-label=\"A Simple Blog Post\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/keepinltd.com\/en\/2015\/10\/13\/a-simple-blog-post\/\" class=\"plain\">A Simple Blog Post<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tLorem ipsum dol [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">13<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Oct<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item has-post-icon\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:200px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/keepinltd.com\/en\/2014\/01\/01\/a-video-blog-post\/\" class=\"plain\" aria-label=\"A Video Blog Post\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t\t\t<div class=\"absolute no-click x50 y50 md-x50 md-y50 lg-x50 lg-y50\">\n  \t\t\t\t            \t<div class=\"overlay-icon\">\n  \t\t\t\t                    <i class=\"icon-play\"><\/i>\n  \t\t\t\t                <\/div>\n  \t\t\t\t            <\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/keepinltd.com\/en\/2014\/01\/01\/a-video-blog-post\/\" class=\"plain\">A Video Blog Post<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tLorem ipsum dol [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">01<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Jan<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:200px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/keepinltd.com\/en\/2013\/12\/30\/just-a-cool-blog-post-with-images\/\" class=\"plain\" aria-label=\"Just a cool blog post with Images\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/keepinltd.com\/en\/2013\/12\/30\/just-a-cool-blog-post-with-images\/\" class=\"plain\">Just a cool blog post with Images<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tLorem ipsum dol [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">30<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Dec<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:200px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/keepinltd.com\/en\/2013\/12\/16\/just-a-cool-blog-post-with-a-gallery-2\/\" class=\"plain\" aria-label=\"Another post with A Gallery\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/keepinltd.com\/en\/2013\/12\/16\/just-a-cool-blog-post-with-a-gallery-2\/\" class=\"plain\">Another post with A Gallery<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tLorem ipsum dol [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">16<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Dec<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-bold-center\"><b><\/b><span class=\"section-title-main\" style=\"font-size:undefined%;\"><i class=\"icon-instagram\" ><\/i>Follow on instagram<\/span><b><\/b><\/h3><\/div>\nNo images found.\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":21,"parent":75,"menu_order":8,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"class_list":["post-39","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grid Style 3 - KeepIn Contracting Limited<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/keepinltd.com\/en\/demos\/shop-demos\/grid-style-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grid Style 3 - KeepIn Contracting Limited\" \/>\n<meta property=\"og:url\" content=\"https:\/\/keepinltd.com\/en\/demos\/shop-demos\/grid-style-3\/\" \/>\n<meta property=\"og:site_name\" content=\"KeepIn Contracting Limited\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-09T10:40:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"260\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/keepinltd.com\\\/demos\\\/shop-demos\\\/grid-style-3\\\/\",\"url\":\"https:\\\/\\\/keepinltd.com\\\/demos\\\/shop-demos\\\/grid-style-3\\\/\",\"name\":\"Grid Style 3 - KeepIn Contracting Limited\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/keepinltd.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/keepinltd.com\\\/demos\\\/shop-demos\\\/grid-style-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/keepinltd.com\\\/demos\\\/shop-demos\\\/grid-style-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/keepinltd.com\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/dummy-1.jpg\",\"datePublished\":\"2016-07-05T14:49:02+00:00\",\"dateModified\":\"2025-02-09T10:40:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/keepinltd.com\\\/demos\\\/shop-demos\\\/grid-style-3\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/keepinltd.com\\\/demos\\\/shop-demos\\\/grid-style-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/keepinltd.com\\\/demos\\\/shop-demos\\\/grid-style-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/keepinltd.com\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/dummy-1.jpg\",\"contentUrl\":\"https:\\\/\\\/keepinltd.com\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/dummy-1.jpg\",\"width\":400,\"height\":260},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/keepinltd.com\\\/demos\\\/shop-demos\\\/grid-style-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9801\",\"item\":\"https:\\\/\\\/keepinltd.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Demos\",\"item\":\"https:\\\/\\\/keepinltd.com\\\/demos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Shop Demos\",\"item\":\"https:\\\/\\\/keepinltd.com\\\/demos\\\/shop-demos\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Grid Style 3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/keepinltd.com\\\/#website\",\"url\":\"https:\\\/\\\/keepinltd.com\\\/\",\"name\":\"KeepIn Contracting Limited\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/keepinltd.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grid Style 3 - KeepIn Contracting Limited","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/keepinltd.com\/en\/demos\/shop-demos\/grid-style-3\/","og_locale":"en_US","og_type":"article","og_title":"Grid Style 3 - KeepIn Contracting Limited","og_url":"https:\/\/keepinltd.com\/en\/demos\/shop-demos\/grid-style-3\/","og_site_name":"KeepIn Contracting Limited","article_modified_time":"2025-02-09T10:40:07+00:00","og_image":[{"width":400,"height":260,"url":"https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/keepinltd.com\/demos\/shop-demos\/grid-style-3\/","url":"https:\/\/keepinltd.com\/demos\/shop-demos\/grid-style-3\/","name":"Grid Style 3 - KeepIn Contracting Limited","isPartOf":{"@id":"https:\/\/keepinltd.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/keepinltd.com\/demos\/shop-demos\/grid-style-3\/#primaryimage"},"image":{"@id":"https:\/\/keepinltd.com\/demos\/shop-demos\/grid-style-3\/#primaryimage"},"thumbnailUrl":"https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-1.jpg","datePublished":"2016-07-05T14:49:02+00:00","dateModified":"2025-02-09T10:40:07+00:00","breadcrumb":{"@id":"https:\/\/keepinltd.com\/demos\/shop-demos\/grid-style-3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/keepinltd.com\/demos\/shop-demos\/grid-style-3\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/keepinltd.com\/demos\/shop-demos\/grid-style-3\/#primaryimage","url":"https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-1.jpg","contentUrl":"https:\/\/keepinltd.com\/wp-content\/uploads\/2016\/08\/dummy-1.jpg","width":400,"height":260},{"@type":"BreadcrumbList","@id":"https:\/\/keepinltd.com\/demos\/shop-demos\/grid-style-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9801","item":"https:\/\/keepinltd.com\/"},{"@type":"ListItem","position":2,"name":"Demos","item":"https:\/\/keepinltd.com\/demos\/"},{"@type":"ListItem","position":3,"name":"Shop Demos","item":"https:\/\/keepinltd.com\/demos\/shop-demos\/"},{"@type":"ListItem","position":4,"name":"Grid Style 3"}]},{"@type":"WebSite","@id":"https:\/\/keepinltd.com\/#website","url":"https:\/\/keepinltd.com\/","name":"KeepIn Contracting Limited","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/keepinltd.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/keepinltd.com\/en\/wp-json\/wp\/v2\/pages\/39","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/keepinltd.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/keepinltd.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/keepinltd.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/keepinltd.com\/en\/wp-json\/wp\/v2\/comments?post=39"}],"version-history":[{"count":1,"href":"https:\/\/keepinltd.com\/en\/wp-json\/wp\/v2\/pages\/39\/revisions"}],"predecessor-version":[{"id":110,"href":"https:\/\/keepinltd.com\/en\/wp-json\/wp\/v2\/pages\/39\/revisions\/110"}],"up":[{"embeddable":true,"href":"https:\/\/keepinltd.com\/en\/wp-json\/wp\/v2\/pages\/75"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/keepinltd.com\/en\/wp-json\/wp\/v2\/media\/21"}],"wp:attachment":[{"href":"https:\/\/keepinltd.com\/en\/wp-json\/wp\/v2\/media?parent=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}